{"id":1786,"count":1,"description":"","link":"https:\/\/www.cvm.org.uk\/blog\/tag\/whisky\/","name":"whisky","slug":"whisky","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.cvm.org.uk\/blog\/wp-json\/wp\/v2\/tags\/1786"}],"collection":[{"href":"https:\/\/www.cvm.org.uk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cvm.org.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cvm.org.uk\/blog\/wp-json\/wp\/v2\/posts?tags=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}